{"id":5480,"date":"2020-09-07T14:08:16","date_gmt":"2020-09-07T12:08:16","guid":{"rendered":"https:\/\/www.perfectvanwamel.com\/unkategorisiert\/variochop-universalhaecksler\/"},"modified":"2020-10-05T15:48:11","modified_gmt":"2020-10-05T13:48:11","slug":"variochop-universalhaecksler","status":"publish","type":"post","link":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/","title":{"rendered":"VARIOCHOP Universalh\u00e4cksler"},"content":{"rendered":"<p>Mit den VARIOCHOP Universalh\u00e4ckslern f\u00fcr Gras und Holzschnitt bieten wir eine L\u00f6sung f\u00fcr ein Problem, das vielen Obst- und Weinbauern nicht unbekannt sein d\u00fcrfte.<\/p>\n<p>Die robusten VARIOCHOP H\u00e4cksler, die sich sowohl f\u00fcr den Front- als auch f\u00fcr den Heckanbau an einem Traktor eignen, sind so konzipiert, dass Sie nicht mehr zwischen verschiedenen Gelenkwellendrehzahlen w\u00e4hlen m\u00fcssen.<\/p>\n<ul>\n<li>Ein spezieller Anbaubock macht den Einsatz sowohl vor<br \/>\nals auch hinter der Zugmaschine m\u00f6glich\u00a0\u2013 ganz ohne Umbau.<\/li>\n<li>Von der Drehrichtung unabh\u00e4ngiges Zahnradgetriebe mit<br \/>\nintegriertem Freilauf<\/li>\n<li>Einsetzbar f\u00fcr 540, 750 und 1000 U\/min durch einfache<br \/>\nVerstellung der Keilriemenscheiben<\/li>\n<li>Hydraulische Seitenverstellm\u00f6glichkeit: 48\u00a0cm (ausgenommen das 135-cm-Modell)<\/li>\n<\/ul>\n<p><strong>Spezialh\u00e4cksler f\u00fcr Obstbaubetriebe<\/strong><\/p>\n<ul>\n<li>Abgesenkter Keilriemenantrieb; H\u00f6he der Keilriemenabdeckungen: 51,5\u00a0cm<\/li>\n<li>Verst\u00e4rkte Bauform f\u00fcr Holzschnitt bis 8\u00a0cm Durchschnitt<\/li>\n<li>Die Schlegel sind mit schweren 20-mm-Schrauben und auswechselbaren Stahlh\u00fclsen an der zweifach elektronisch ausgewuchteten Schlegelwelle befestigt.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mit den VARIOCHOP Universalh\u00e4ckslern f\u00fcr Gras und Holzschnitt bieten wir eine L\u00f6sung f\u00fcr ein Problem, das vielen Obst- und Weinbauern nicht unbekannt sein d\u00fcrfte. Die robusten VARIOCHOP H\u00e4cksler, die sich sowohl f\u00fcr den Front- als auch f\u00fcr den Heckanbau an einem Traktor eignen, sind so konzipiert, dass Sie nicht mehr zwischen verschiedenen Gelenkwellendrehzahlen w\u00e4hlen m\u00fcssen&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":4562,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1004],"tags":[],"class_list":["post-5480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VARIOCHOP Universalh\u00e4cksler - PERFECT - Van Wamel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VARIOCHOP Universalh\u00e4cksler - PERFECT - Van Wamel\" \/>\n<meta property=\"og:description\" content=\"Mit den VARIOCHOP Universalh\u00e4ckslern f\u00fcr Gras und Holzschnitt bieten wir eine L\u00f6sung f\u00fcr ein Problem, das vielen Obst- und Weinbauern nicht unbekannt sein d\u00fcrfte. Die robusten VARIOCHOP H\u00e4cksler, die sich sowohl f\u00fcr den Front- als auch f\u00fcr den Heckanbau an einem Traktor eignen, sind so konzipiert, dass Sie nicht mehr zwischen verschiedenen Gelenkwellendrehzahlen w\u00e4hlen m\u00fcssen....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/\" \/>\n<meta property=\"og:site_name\" content=\"PERFECT - Van Wamel\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-07T12:08:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-05T13:48:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.perfectvanwamel.com\/wp-content\/uploads\/2019\/08\/variochop-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/#\\\/schema\\\/person\\\/ecb1390bcc04352dcb7ac0e1f6f0cf57\"},\"headline\":\"VARIOCHOP Universalh\u00e4cksler\",\"datePublished\":\"2020-09-07T12:08:16+00:00\",\"dateModified\":\"2020-10-05T13:48:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/\"},\"wordCount\":151,\"image\":{\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/variochop-1-scaled.jpg\",\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/\",\"url\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/\",\"name\":\"VARIOCHOP Universalh\u00e4cksler - PERFECT - Van Wamel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/variochop-1-scaled.jpg\",\"datePublished\":\"2020-09-07T12:08:16+00:00\",\"dateModified\":\"2020-10-05T13:48:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/#\\\/schema\\\/person\\\/ecb1390bcc04352dcb7ac0e1f6f0cf57\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/variochop-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/variochop-1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/nachrichten\\\/variochop-universalhaecksler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staging.perfectvanwamel.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VARIOCHOP Universalh\u00e4cksler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/\",\"name\":\"PERFECT - Van Wamel\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/de\\\/#\\\/schema\\\/person\\\/ecb1390bcc04352dcb7ac0e1f6f0cf57\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/ab4dd8c40ffc779fa1ef9441318ade00.jpg?ver=1778670008\",\"url\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/ab4dd8c40ffc779fa1ef9441318ade00.jpg?ver=1778670008\",\"contentUrl\":\"https:\\\/\\\/www.perfectvanwamel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/ab4dd8c40ffc779fa1ef9441318ade00.jpg?ver=1778670008\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VARIOCHOP Universalh\u00e4cksler - PERFECT - Van Wamel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/","og_locale":"de_DE","og_type":"article","og_title":"VARIOCHOP Universalh\u00e4cksler - PERFECT - Van Wamel","og_description":"Mit den VARIOCHOP Universalh\u00e4ckslern f\u00fcr Gras und Holzschnitt bieten wir eine L\u00f6sung f\u00fcr ein Problem, das vielen Obst- und Weinbauern nicht unbekannt sein d\u00fcrfte. Die robusten VARIOCHOP H\u00e4cksler, die sich sowohl f\u00fcr den Front- als auch f\u00fcr den Heckanbau an einem Traktor eignen, sind so konzipiert, dass Sie nicht mehr zwischen verschiedenen Gelenkwellendrehzahlen w\u00e4hlen m\u00fcssen....","og_url":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/","og_site_name":"PERFECT - Van Wamel","article_published_time":"2020-09-07T12:08:16+00:00","article_modified_time":"2020-10-05T13:48:11+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/staging.perfectvanwamel.com\/wp-content\/uploads\/2019\/08\/variochop-1-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/#article","isPartOf":{"@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/"},"author":{"name":"admin","@id":"https:\/\/www.perfectvanwamel.com\/de\/#\/schema\/person\/ecb1390bcc04352dcb7ac0e1f6f0cf57"},"headline":"VARIOCHOP Universalh\u00e4cksler","datePublished":"2020-09-07T12:08:16+00:00","dateModified":"2020-10-05T13:48:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/"},"wordCount":151,"image":{"@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perfectvanwamel.com\/wp-content\/uploads\/2019\/08\/variochop-1-scaled.jpg","articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/","url":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/","name":"VARIOCHOP Universalh\u00e4cksler - PERFECT - Van Wamel","isPartOf":{"@id":"https:\/\/www.perfectvanwamel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/#primaryimage"},"image":{"@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perfectvanwamel.com\/wp-content\/uploads\/2019\/08\/variochop-1-scaled.jpg","datePublished":"2020-09-07T12:08:16+00:00","dateModified":"2020-10-05T13:48:11+00:00","author":{"@id":"https:\/\/www.perfectvanwamel.com\/de\/#\/schema\/person\/ecb1390bcc04352dcb7ac0e1f6f0cf57"},"breadcrumb":{"@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/#primaryimage","url":"https:\/\/www.perfectvanwamel.com\/wp-content\/uploads\/2019\/08\/variochop-1-scaled.jpg","contentUrl":"https:\/\/www.perfectvanwamel.com\/wp-content\/uploads\/2019\/08\/variochop-1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.perfectvanwamel.com\/de\/nachrichten\/variochop-universalhaecksler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.perfectvanwamel.com\/de\/"},{"@type":"ListItem","position":2,"name":"VARIOCHOP Universalh\u00e4cksler"}]},{"@type":"WebSite","@id":"https:\/\/www.perfectvanwamel.com\/de\/#website","url":"https:\/\/www.perfectvanwamel.com\/de\/","name":"PERFECT - Van Wamel","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perfectvanwamel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.perfectvanwamel.com\/de\/#\/schema\/person\/ecb1390bcc04352dcb7ac0e1f6f0cf57","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.perfectvanwamel.com\/wp-content\/litespeed\/avatar\/ab4dd8c40ffc779fa1ef9441318ade00.jpg?ver=1778670008","url":"https:\/\/www.perfectvanwamel.com\/wp-content\/litespeed\/avatar\/ab4dd8c40ffc779fa1ef9441318ade00.jpg?ver=1778670008","contentUrl":"https:\/\/www.perfectvanwamel.com\/wp-content\/litespeed\/avatar\/ab4dd8c40ffc779fa1ef9441318ade00.jpg?ver=1778670008","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/posts\/5480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/comments?post=5480"}],"version-history":[{"count":1,"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/posts\/5480\/revisions"}],"predecessor-version":[{"id":6974,"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/posts\/5480\/revisions\/6974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/media\/4562"}],"wp:attachment":[{"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/media?parent=5480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/categories?post=5480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.perfectvanwamel.com\/de\/wp-json\/wp\/v2\/tags?post=5480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}